{"id":695,"date":"2016-05-09T10:29:29","date_gmt":"2016-05-09T10:29:29","guid":{"rendered":"http:\/\/sefarad-asturias.org\/blog\/?p=695"},"modified":"2020-08-03T21:38:52","modified_gmt":"2020-08-03T21:38:52","slug":"el-eslabon-que-nos-une-las-mitsvot","status":"publish","type":"post","link":"http:\/\/sefarad-asturias.org\/blog\/el-eslabon-que-nos-une-las-mitsvot\/","title":{"rendered":"El eslab\u00f3n que nos une (las mitsvot)"},"content":{"rendered":"\n<p>Nuestros abuelos bajaron del barco con los bolsillos vac\u00edos y las maletas repletas, si las ten\u00edan, un diccionario implacable y los recuerdos del resplandor de la casa europea. Los afortunados, los que lograron saltar el mar del abismo para empezar desde cero, no tuvieron m\u00e1s opci\u00f3n, desde ese mismo amanecer, que trabajar para sustentar al cuerpo y salir adelante en pa\u00edses lejanos.<\/p>\n<p><a href=\"http:\/\/sefarad-asturias.org\/wp\/wp-content\/uploads\/2016\/05\/Barco-de-emigrantes.jpeg\" rel=\"attachment wp-att-1382\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1382\" src=\"http:\/\/sefarad-asturias.org\/wp\/wp-content\/uploads\/2016\/05\/Barco-de-emigrantes.jpeg\" sizes=\"auto, (max-width: 1467px) 100vw, 1467px\" srcset=\"http:\/\/sefarad-asturias.org\/wp\/wp-content\/uploads\/2016\/05\/Barco-de-emigrantes.jpeg 1467w, http:\/\/sefarad-asturias.org\/wp\/wp-content\/uploads\/2016\/05\/Barco-de-emigrantes-300x212.jpeg 300w, http:\/\/sefarad-asturias.org\/wp\/wp-content\/uploads\/2016\/05\/Barco-de-emigrantes-768x542.jpeg 768w, http:\/\/sefarad-asturias.org\/wp\/wp-content\/uploads\/2016\/05\/Barco-de-emigrantes-1024x722.jpeg 1024w\" alt=\"Barco de emigrantes jud\u00edos\" width=\"333\" height=\"235\" \/><\/a><\/p>\n<p>Sus hijos, que hablaron dos idiomas, el de casa y el del pa\u00eds que los acogi\u00f3, se sentaron a estudiar en la mesa de la cocina mientras la madre lavaba los platos, se esforzaron en estudiar mucho, se recibieron de maestros, de ingenieros o de abogados, y le pudieron ganar la batalla al exilio, sinti\u00e9ndose ciudadanos del pa\u00eds que habitaban.<\/p>\n<p>Y nosotros, los hijos de los hijos, gracias a que ten\u00edamos el est\u00f3mago lleno y la cabeza atiborrada, nos estamos alejando de los eslabones que nos unen con las generaciones pasadas.<\/p>\n<p>Por ello debemos tener la fuerza de reabrir la puerta espiritual, esa que se entrecerr\u00f3 cuando se construyeron sinagogas y no casas de estudio, provocando que se olvidara el sentido y el gusto de la religi\u00f3n (excepto el del guefilte fish de la abuela y la asistencia ocasional al rezo).<\/p>\n<p>Las mitsvot tienen la funci\u00f3n de conectarnos con el origen. Son una cadena que nos enlaza con el punto original. La mitsv\u00e1 de kibud orim (honrar a nuestros padres), nos conecta con nuestro origen m\u00e1s inmediato. Y ayuda a proteger esos eslabones con u\u00f1as y dientes. Sean quienes sean, nuestros padres merecen ser honrados, no por lo que nos dan o nos dar\u00e1n, sino por lo que ya nos han aportado al nacer.<\/p>\n<p>Hacer esto, olvidar el pasado, es como no reconocer que la flor se debe al esfuerzo de la ra\u00edz, al del tallo, al de las hojas. Es como creer que nos hicimos a nosotros mismos, es como creer que de alguna manera nos hubi\u00e9semos arreglado para existir, m\u00e1s all\u00e1 de nuestros padres.<\/p>\n<p>Nuestro concepto de libertad nos incita a romper esa cadena para sentirnos libres de la atadura con el pasado, pero no nos damos cuenta de que en este caso, liberarnos significa encadenarnos a otras acciones que no alimentan el alma. Y ello provocar\u00e1 que la cadena se acabe\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestros abuelos bajaron del barco con los bolsillos vac\u00edos y las maletas repletas, si las ten\u00edan, un diccionario implacable y los recuerdos del resplandor de la casa europea. Los afortunados, los que lograron saltar el mar del abismo para empezar desde cero, no tuvieron m\u00e1s opci\u00f3n, desde ese mismo amanecer, que trabajar para sustentar al &#8230; <a title=\"El eslab\u00f3n que nos une (las mitsvot)\" class=\"read-more\" href=\"http:\/\/sefarad-asturias.org\/blog\/el-eslabon-que-nos-une-las-mitsvot\/\" aria-label=\"Leer m\u00e1s sobre El eslab\u00f3n que nos une (las mitsvot)\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-695","post","type-post","status-publish","format-standard","hentry","category-herencia-judia"],"_links":{"self":[{"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/posts\/695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/comments?post=695"}],"version-history":[{"count":0,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/posts\/695\/revisions"}],"wp:attachment":[{"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/media?parent=695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/categories?post=695"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/tags?post=695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}