{"id":1650,"date":"2014-12-12T11:17:27","date_gmt":"2014-12-12T11:17:27","guid":{"rendered":"http:\/\/sefarad-asturias.org\/blog\/?p=1650"},"modified":"2021-05-30T09:25:27","modified_gmt":"2021-05-30T09:25:27","slug":"parashat-vaieshev-historias-dificiles","status":"publish","type":"post","link":"http:\/\/sefarad-asturias.org\/blog\/parashat-vaieshev-historias-dificiles\/","title":{"rendered":"PARASHAT VAIESHEV: Historias dif\u00edciles"},"content":{"rendered":"\n<p>Esta serie de parshiot que se inaugura con Vaieshev va a llevarnos por la dram\u00e1tica de vida de Iosef y sus hermanos. Cada cap\u00edtulo presenta nuevas dificultades, historias dif\u00edciles de elaborar porque hablan de subjetividades entrampadas en din\u00e1micas familiares mal resueltas.<\/p>\n<p>Iosef es marcadamente el preferido de su padre delante de sus hermanos. Ellos se celan. \u00c9l se aprovecha de esas preferencias y se muestra superior a ellos, sin tapujos. Sus actitudes y relatos les despiertan a sus hermanos, un profundo odio.<\/p>\n<p>Shim\u00f3n y Levi, dos de ellos, planean matarlo, pero Reuv\u00e9n sugiere, a cambio, arrojarlo en un pozo, con la intenci\u00f3n de volver m\u00e1s tarde y salvarlo. Mientras Iosef est\u00e1 en el pozo, Iehuda lo vende a una caravana de Ishmaelitas. Los hermanos manchan la t\u00fanica especial que vest\u00eda s\u00f3lo Iosef con sangre de un cabrito y se lo muestran a su padre, haci\u00e9ndole pensar que su m\u00e1s querido hijo fue devorado por una bestia salvaje.<\/p>\n<p>La parash\u00e1 sigue con relatos traum\u00e1ticos, pero vamos a ver a Iosef en el pozo.<\/p>\n<p>Dos hermanos quieren matarlo directamente y un tercero, Reuv\u00e9n intercede y negocia un castigo menor: tirarlo a un pozo. No hac\u00eda falta matarlo para que aprenda la lecci\u00f3n.<\/p>\n<p>Rashi nos va a decir que la intenci\u00f3n de Reuv\u00e9n era salvar a Iosef para regresarlo a su padre.<\/p>\n<p>Entonces \u00bfc\u00f3mo fue que otro hermano lo vende a una caravana de ishmaelitas? \u00bfD\u00f3nde estaba Reuv\u00e9n en esta escena?<\/p>\n<p>De hecho sabemos que no estaba all\u00ed cerca del pozo porque la Tor\u00e1 dice:<\/p>\n<p>\u201c<em>Cuando Reuv\u00e9n volvi\u00f3 al pozo, he aqu\u00ed, Iosef no estaba en el pozo; entonces rasg\u00f3 sus vestidos. Y volvi\u00f3 a sus hermanos y les dijo: El muchacho no est\u00e1 all\u00ed; y yo, \u00bfad\u00f3nde ir\u00e9<\/em>?\u201d Bereshit 37: 29-30<\/p>\n<p>\u00c9l, que lo hab\u00eda salvado del asesinato, de pronto est\u00e1 ausente en el momento de la venta\u2026 \u00bfqu\u00e9 era lo importante que deb\u00eda hacer en ese momento?<\/p>\n<p>Rashi nos vuelve a ayudar a responder esta respuesta y trae dos explicaciones:<\/p>\n<p>Una: Reuv\u00e9n no estaba all\u00ed porque los hermanos se turnaban para volver a su casa y cuidar del padre.<\/p>\n<p>La segunda: Reuv\u00e9n se alej\u00f3 para hacer teshuv\u00e1, ayunando y vistiendo un saco (a la manera del duelo) para reflexionar por un episodio con el que concluye la parash\u00e1 pasada en el que tiene relaciones con Bilh\u00e1, la concubina de su padre.<\/p>\n<p>Muchos comentaristas responsabilizan a Reuv\u00e9n finalmente, por el destino tortuoso de Iosef. Iosef es vendido como esclavo, termina en la c\u00e1rcel. Reuv\u00e9n fue a hacer teshuv\u00e1 para redimirse a s\u00ed mismo, cuando un hermano suyo estaba en el pozo.<\/p>\n<p>A todos nos pasa algo inquietante con el s\u00edmbolo del pozo. Sobre el que se han escrito m\u00faltiples interpretaciones. No es cualquier lugar. Un hermano est\u00e1 en el pozo. Solo. El pozo, para las mitolog\u00edas alude al reino inferior y el acceso al mundo de los muertos. Psicol\u00f3gicamente, el pozo se relaciona con lo inconsciente, lo oculto, lo que se esconde y es inaccesible para la vida cotidiana.<\/p>\n<p>\u00bfQui\u00e9n no ha tenido alguna vez la sensaci\u00f3n de haber ca\u00eddo en un pozo?<\/p>\n<p>Lo que tambi\u00e9n sabemos es que del pozo no se sale solo. Y Reuv\u00e9n era la persona que deb\u00eda haberlo sacado de all\u00ed, una vez que los salvara de las garras de sus hermanos.<\/p>\n<p>Pero no. Prioriz\u00f3 su necesidad de liberarse de la culpa de haber pecado acost\u00e1ndose con la concubina de su padre, ante la desesperaci\u00f3n que deber\u00eda haber sentido su hermano, dentro del pozo.<\/p>\n<p>Luego retorna y se rasga las vestiduras. Tarde. Ninguna se\u00f1al de duelo reemplaza la responsabilidad por hacerse cargo del otro, en el momento en el que el otro lo necesita.<\/p>\n<p>Cu\u00e1ntas veces ponemos como excusas que tenemos mucho por ocuparnos de nosotros mismos por lo tanto no nos podemos hacer cargo de otros.<\/p>\n<p>Hay circunstancias que nos obligan a no priorizarnos. A no ponernos de escudos protectores ante nuestra responsabilidad por el otro, sobre todo cuando sabemos que solo no podr\u00e1 salir de ese pozo.<\/p>\n<p>Cu\u00e1ntas veces ponemos excusas acerca de nuestros gastos, para no darle una mano a quien se est\u00e1 ahogando econ\u00f3micamente. Cu\u00e1ntas veces anteponemos nuestras obligaciones sociales y argumentamos que no tenemos tiempo de ir a visitar a nuestros mayores; aquellos que quiz\u00e1s esperan una semana entera para ser mirados por alguien de su familia.<\/p>\n<p>Cu\u00e1ntas veces agrandamos nuestras propias necesidades para excusarnos de ver a los que realmente est\u00e1n necesitando de nuestra ayuda y presencia.<\/p>\n<p>Cu\u00e1ntas veces somos Reuv\u00e9n. Cu\u00e1ntas veces somos Iosef.<\/p>\n<p>Al volver ser lament\u00f3 y rasg\u00f3 sus vestiduras. Era tarde.<\/p>\n<p>Iosef ya no estaba. Fue vendido, esclavizado, y la historia devino en 400 a\u00f1os de opresi\u00f3n y tortura.<\/p>\n<p>Una presencia a tiempo hubiera modificado la historia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta serie de parshiot que se inaugura con Vaieshev va a llevarnos por la dram\u00e1tica de vida de Iosef y sus hermanos. Cada cap\u00edtulo presenta nuevas dificultades, historias dif\u00edciles de elaborar porque hablan de subjetividades entrampadas en din\u00e1micas familiares mal resueltas. Iosef es marcadamente el preferido de su padre delante de sus hermanos. Ellos se &#8230; <a title=\"PARASHAT VAIESHEV: Historias dif\u00edciles\" class=\"read-more\" href=\"http:\/\/sefarad-asturias.org\/blog\/parashat-vaieshev-historias-dificiles\/\" aria-label=\"Leer m\u00e1s sobre PARASHAT VAIESHEV: Historias dif\u00edciles\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[200],"class_list":["post-1650","post","type-post","status-publish","format-standard","hentry","category-parashat-hashavua","tag-vaieshev"],"_links":{"self":[{"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/posts\/1650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/comments?post=1650"}],"version-history":[{"count":0,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/posts\/1650\/revisions"}],"wp:attachment":[{"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/media?parent=1650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/categories?post=1650"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/tags?post=1650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}