{"id":1267,"date":"2016-09-03T20:53:56","date_gmt":"2016-09-03T20:53:56","guid":{"rendered":"http:\/\/sefarad-asturias.org\/blog\/?p=1267"},"modified":"2020-09-07T09:56:12","modified_gmt":"2020-09-07T09:56:12","slug":"rosh-hashana-yom-trua","status":"publish","type":"post","link":"http:\/\/sefarad-asturias.org\/blog\/rosh-hashana-yom-trua\/","title":{"rendered":"ROSH HASHAN\u00c1: YOM TRU\u00c1"},"content":{"rendered":"\n<p>Dado que se trata del d\u00eda del juicio recibe el nombre de \u00abD\u00eda del Toque del Shofar\u00bb o \u00abYom Tru\u00e1\u00bb (Bamidbar \u2013 N\u00fameros 29:1). A diferencia del sonido de la \u00abteki\u00e1\u00bb (sonido fuerte y prolongado) que simboliza alegr\u00eda y estabilidad, el sonido de la \u00abtru\u00e1\u00bb (entrecortado) insin\u00faa quebrantamiento del coraz\u00f3n, temor, llanto y cambio radical de la presente situaci\u00f3n. Onkelos tradujo al arameo \u00abd\u00eda de toque del Shofar\u00bb como \u00abd\u00eda de lamento y llanto\u00bb.<\/p>\n<p>Asimismo, vemos que Hashem orden\u00f3 al pueblo de Israel en el desierto que toquen una \u00abteki\u00e1\u00bb con las trompetas cuando sea menester reunirse, ya que este sonido implica alegr\u00eda y encuentro. Mas cuando necesiten salir a la guerra o abandonar un sitio determinado y trasladarse a otro, deben ejecutar con las trompetas una \u00abtru\u00e1\u00bb (Bamidbar 10:1-7). Esto se debe a que la \u00abtru\u00e1\u00bb expresa quebrantamiento y llanto por lo que lleg\u00f3 a su t\u00e9rmino y no logr\u00f3 ser completado, am\u00e9n de temor por la siguiente etapa. Por lo tanto, si cuando se pasa de un sitio a otro el temor es muy grande; mucho mayor a\u00fan es en Rosh Hashan\u00e1 cuando la vida que otorg\u00f3 Hashem para el a\u00f1o que pas\u00f3 lleg\u00f3 a su t\u00e9rmino y la del a\u00f1o a iniciarse a\u00fan no fue adjudicada y no se ha definido a\u00fan qui\u00e9n habr\u00e1 de vivir y qui\u00e9n habr\u00e1 de morir, qui\u00e9n habr\u00e1 de experimentar tranquilidad y qui\u00e9n habr\u00e1 de padecer sufrimientos. Todo depende del veredicto del juicio, Hashem adjudica vida a las personas para el a\u00f1o entrante de acuerdo a sus acciones pasadas.<\/p>\n<p>Por ello, el coraz\u00f3n se llena de temor al recordar la enorme responsabilidad que nuestro D\u00b4s deposit\u00f3 sobre nuestros hombros para darle continuidad a este mundo y repararlo. Las personas se despiertan para meditar sobre lo realizado, \u00bfacaso cumplieron con su cometido o decepcionaron? Por lo tanto, si bien el tiempo en el cual se toca el sonido de \u00abtru\u00e1\u00bb es breve, todo el d\u00eda es denominado \u00abD\u00eda de Toque de Tru\u00e1\u00bb, d\u00eda de quebrantamiento y llanto, temor \u00a0y miedo.<\/p>\n<p>En Rosh Hashan\u00e1 se nos orden\u00f3 tocar el sonido de \u00abtru\u00e1\u00bb de un Shofar y no de una trompeta, ya que el primero expresa m\u00e1s cabalmente el sonido en cuesti\u00f3n que se asemeja a la voz del coraz\u00f3n, un sonido natural anterior a toda verbalizaci\u00f3n, m\u00e1s b\u00e1sico a\u00fan que el gemido o el llanto comunes. Se trata de un sonido que puede expresar el enorme dolor ocasionado por la mentira y el dolo, la negligencia y la alevos\u00eda; por la enorme brecha que media entre el hombre y su Creador y la gran distancia que hay entre nuestras aspiraciones ideales y nuestra vida real en la pr\u00e1ctica (Shel\u00e1 o <em>Shnei Lujot Habrit<\/em> sobre Rosh Hashan\u00e1 en <em>Tor\u00e1 Or<\/em> 55).<\/p>\n<p>Tocar el Shofar en Rosh Hashan\u00e1 es un buen precepto que nos orden\u00f3 Hashem para de esta manera reconocer con humildad Su Reinado: \u00a0\u00a0justamente mediante el dolor y el llanto insinuados en el sonido de la \u00abtru\u00e1\u00bb quedan sin efecto las acusaciones que penden contra nosotros y salimos airosos del juicio. Respecto de esto, nuestros sabios, de bendita memoria, dijeron (\u00eddem <em>Rosh Hashan\u00e1<\/em> 16(B)) que \u00abtodo a\u00f1o que inicia con pobreza culmina con abundancia, tal como est\u00e1 escrito (Dvarim \u2013 Deuteronomio 11:12): \u00abdesde el principio del a\u00f1o hasta su fin\u00bb<sup><a id=\"_yn15ftnref3_1\" class=\"aup1\" href=\"https:\/\/ph.yhb.org.il\/es\/15-03-02\/#_yn15ftn3_1\">[1]<\/a><\/sup><\/p>\n<p>Sin embargo se nos orden\u00f3 rodear el sonido de \u00abtru\u00e1\u00bb con otros que aluden a la estabilidad y la alegr\u00eda (\u00abtki\u00e1\u00bb), ya que si nos retrotraemos a la ra\u00edz de la cuesti\u00f3n, vemos que el rigor y los padecimientos est\u00e1n orientados al bien de la persona y su reparaci\u00f3n.<\/p>\n<p>Se dice en nombre del Ar\u00ed z\u00bbl que es bueno que la persona llore en Rosh Hashan\u00e1, y quien no lo hace es se\u00f1al de que su alma no es ni recta ni completa (<em>Shaar Hakavanot<\/em> 90:1). Este llanto es la expresi\u00f3n del \u00abD\u00eda de la Tru\u00e1\u00bb, esto es, d\u00eda de sollozos y llanto. Sin embargo, Rosh Hashan\u00e1 es tambi\u00e9n \u00abD\u00eda de Santa Congregaci\u00f3n\u00bb (\u00abMikr\u00e1 Kodesh\u00bb) y por ende es preceptivo alegrarse. El llanto de este d\u00eda no es de desesperanza y depresi\u00f3n sino de anhelo por un nivel espiritual superior. Se trata de un llanto de dolor por todo lo que a\u00fan no hemos logrado reparar, y de emoci\u00f3n por el enorme m\u00e9rito que se nos concede y es el de poder presentarnos ante \u00c9l; m\u00e9rito por la misi\u00f3n que nos encomend\u00f3 el Creador y el alma sagrada que insufl\u00f3 en nuestro interior. En el d\u00eda del juicio este llanto nos causa placer y alegr\u00eda interior pues expresa la verdad y nos conduce a la reparaci\u00f3n y la bendici\u00f3n. Estos son los dos aspectos de Rosh Hashan\u00e1, \u00abD\u00eda de Santa congregaci\u00f3n\u00bb y \u00abD\u00eda de Tru\u00e1\u00bb, esta dualidad se expresa en los sonidos de \u00abtki\u00e1\u00bb y \u00abtru\u00e1\u00bb.<\/p>\n<p>FUENTE: Pninei Halaj\u00e1<\/p>\n<div>\n<hr size=\"1\" \/>\n<div><a id=\"_yn15ftn3_1\" href=\"https:\/\/ph.yhb.org.il\/es\/15-03-02\/#_yn15ftnref3_1\">[1]<\/a>. En el vers\u00edculo citado la palabra \u00abprincipio\u00bb est\u00e1 sorprendentemente escrita sin la letra hebrea \u05d0 \u00a0lo cual la asemeja al vocablo pobreza, los sabios interpretaron esta anomal\u00eda ortogr\u00e1fica como una insinuaci\u00f3n de la Tor\u00e1 respecto de que el principio del a\u00f1o puede ser pobre, mas, como el inicio del vers\u00edculo lo indica, esto obedece a la Providencia Divina por lo que al final del mismo la bendici\u00f3n ha de llegar (n. de t.)<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dado que se trata del d\u00eda del juicio recibe el nombre de \u00abD\u00eda del Toque del Shofar\u00bb o \u00abYom Tru\u00e1\u00bb (Bamidbar \u2013 N\u00fameros 29:1). A diferencia del sonido de la \u00abteki\u00e1\u00bb (sonido fuerte y prolongado) que simboliza alegr\u00eda y estabilidad, el sonido de la \u00abtru\u00e1\u00bb (entrecortado) insin\u00faa quebrantamiento del coraz\u00f3n, temor, llanto y cambio radical &#8230; <a title=\"ROSH HASHAN\u00c1: YOM TRU\u00c1\" class=\"read-more\" href=\"http:\/\/sefarad-asturias.org\/blog\/rosh-hashana-yom-trua\/\" aria-label=\"Leer m\u00e1s sobre ROSH HASHAN\u00c1: YOM TRU\u00c1\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[103],"class_list":["post-1267","post","type-post","status-publish","format-standard","hentry","category-fiestas-judias","tag-rosh-hashana"],"_links":{"self":[{"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/posts\/1267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/comments?post=1267"}],"version-history":[{"count":0,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/posts\/1267\/revisions"}],"wp:attachment":[{"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/media?parent=1267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/categories?post=1267"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sefarad-asturias.org\/blog\/wp-json\/wp\/v2\/tags?post=1267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}